{"id":53277,"date":"2026-06-30T11:13:18","date_gmt":"2026-06-30T15:13:18","guid":{"rendered":"\/?page_id=53277"},"modified":"2026-06-30T14:56:51","modified_gmt":"2026-06-30T18:56:51","slug":"vip","status":"publish","type":"page","link":"\/frca\/vip\/","title":{"rendered":"Vip Customer"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbHeader\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb use_background_color_gradient=\u00a0\u00bbon\u00a0\u00bb background_color_gradient_stops=\u00a0\u00bbrgba(34,34,34,0) 0%|rgba(33,15,15,0.45) 100%\u00a0\u00bb background_color_gradient_overlays_image=\u00a0\u00bbon\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2026\/03\/2-1.jpg\u00a0\u00bb custom_padding=\u00a0\u00bb90px||90px||true|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb collapsed=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-1f9b0bb3-481a-49f1-9fe6-999fc3c3182b%22:%91%22background_color_gradient_stops%22%93}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.20.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.20.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bb6e02b861-1c2f-43d5-b7ae-baea8070dac0&Prime; header_font=\u00a0\u00bbMontserrat|700|||||||\u00a0\u00bb header_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_font_size=\u00a0\u00bb65px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||10px||false|false\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb65px\u00a0\u00bb header_font_size_phone=\u00a0\u00bb35px\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_text_shadow_style=\u00a0\u00bbpreset2&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1>CLIENTS VIP BRAVENLY<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb min_height=\u00a0\u00bb278.3px\u00a0\u00bb custom_padding=\u00a0\u00bb40px||40px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb min_height=\u00a0\u00bb111.4px\u00a0\u00bb custom_margin=\u00a0\u00bb|auto|-9px|auto||\u00a0\u00bb custom_padding=\u00a0\u00bb||2px|||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbb9f16d62-6e1a-493e-befd-f1613ea66937&Prime; text_text_color=\u00a0\u00bbgcid-primary-color\u00a0\u00bb header_font=\u00a0\u00bbTenor Sans||||||||\u00a0\u00bb header_3_font=\u00a0\u00bbMontserrat|700|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb40px\u00a0\u00bb custom_margin=\u00a0\u00bb||10px||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-primary-color%22:%91%22text_text_color%22%93}\u00a0\u00bb]<\/p>\n<h3 style=\"text-align: center;\">PR\u00c9PAREZ-VOUS \u00c0 UN TRAITEMENT VIP<\/h3>\n<div style=\"width: 140px; height: 2px; background: #55876a; margin: 10px auto 25px;\"><\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb|1px||||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbLato||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_line_height=\u00a0\u00bb1.5em\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\">Si vous appr\u00e9ciez les produits haut de gamme qui donnent de vrais r\u00e9sultats, devenez client VIP et profitez de rabais, de cadeaux et d\u2019autres avantages incroyables \u00e0 chaque achat. Chez Bravenly, nous traitons nos clients VIP comme des membres de notre famille. <\/p>\n<p style=\"text-align: center;\">Pour vous inscrire, veuillez ajouter les FRAIS D\u2019INSCRIPTION UNIQUES pour clients VIP \u00e0 votre panier! Vous recevrez ensuite vos identifiants de connexion et un lien! <\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb|1px||||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_button button_url=\u00a0\u00bbhttps:\/\/shop.bydesign.com\/Bravenly\/#\/shop\/detail\/VIPMEMBERSHIP\/from\/B5384766\u00a0\u00bb button_text=\u00a0\u00bbD\u00c9BUTER\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb button_text_tablet=\u00a0\u00bbACHETER LES PRODUITS\u00a0\u00bb button_text_phone=\u00a0\u00bbACHETER LES PRODUITS\u00a0\u00bb button_text_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb22px\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_color=\u00a0\u00bbgcid-primary-color\u00a0\u00bb button_border_width=\u00a0\u00bb2px\u00a0\u00bb button_border_color=\u00a0\u00bbgcid-body-color\u00a0\u00bb button_font=\u00a0\u00bbLato||||||||\u00a0\u00bb custom_margin=\u00a0\u00bb10px|10px|10px|10px|false|false\u00a0\u00bb custom_padding=\u00a0\u00bb10px||10px||false|false\u00a0\u00bb button_text_size_tablet=\u00a0\u00bb22px\u00a0\u00bb button_text_size_phone=\u00a0\u00bb16px\u00a0\u00bb button_text_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb hover_transition_duration_tablet=\u00a0\u00bb\u00a0\u00bb hover_transition_duration_phone=\u00a0\u00bb0ms\u00a0\u00bb hover_transition_duration_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-body-color%22:%91%22button_border_color%22%93,%22gcid-primary-color%22:%91%22button_bg_color%22%93}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb min_height=\u00a0\u00bb456.2px\u00a0\u00bb custom_margin=\u00a0\u00bb||1px|||\u00a0\u00bb hover_transition_duration=\u00a0\u00bb0ms\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_3,1_3,1_3&Prime; use_custom_gutter=\u00a0\u00bbon\u00a0\u00bb make_equal=\u00a0\u00bbon\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; min_height=\u00a0\u00bb432.2px\u00a0\u00bb custom_margin=\u00a0\u00bb|auto|119px|auto|false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||3px||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb||80px||false|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb||50px||false|false\u00a0\u00bb custom_css_free_form=\u00a0\u00bb\/* === Make ALL carousel cards the SAME HEIGHT &#038; MATCHING SHADOW === *\/||||\/* Make the slide track stretch all slides equally *\/||selector .slick-track,||selector .swiper-wrapper {||  display: flex !important;||  align-items: stretch !important;||}||||\/* Let each slide fill height *\/||selector .slick-slide,||selector .swiper-slide {||  height: auto !important;||}||||\/* Force card containers to stretch equally *\/||selector .et_pb_blurb,||selector .et_pb_text,||selector .dcb-item,||selector .dcb-slide,||selector .dcb-slide-inner {||  flex: 1 1 auto;||  display: flex;||  flex-direction: column;||  justify-content: space-between;||  height: 100%;||  background: #fff; \/* ensure white cards *\/||  box-shadow: 0 4px 20px rgba(0, 0, 0, 0.1); \/* nice even shadow *\/||  border-radius: 8px; \/* optional rounded corners *\/||  padding: 20px; \/* consistent spacing *\/||}||||\/* Keep buttons at bottom if present *\/||selector .et_pb_button_wrapper,||selector .et_pb_button {||  margin-top: auto;||}||||\/* Justify all text *\/||selector p,||selector .et_pb_text,||selector .et_pb_blurb_description {||  text-align: justify;||  text-justify: inter-word;||}\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb link_option_url=\u00a0\u00bb\/vip-customer\/\u00a0\u00bb link_option_url_new_window=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_blurb title=\u00a0\u00bbPRODUIT\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb image_icon_background_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb image=\u00a0\u00bbhttps:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2026\/03\/4-2.png\u00a0\u00bb image_icon_width=\u00a0\u00bb200%\u00a0\u00bb admin_label=\u00a0\u00bbJuice Type\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; header_font=\u00a0\u00bbMontserrat|700||on|||||\u00a0\u00bb header_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_text_color=\u00a0\u00bb#55876a\u00a0\u00bb header_font_size=\u00a0\u00bb25px\u00a0\u00bb header_line_height=\u00a0\u00bb1.5em\u00a0\u00bb body_font=\u00a0\u00bb||||||||\u00a0\u00bb body_text_align=\u00a0\u00bbcenter\u00a0\u00bb body_text_color=\u00a0\u00bb#0a0000&Prime; body_font_size=\u00a0\u00bb16px\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb background_layout=\u00a0\u00bbdark\u00a0\u00bb min_height=\u00a0\u00bb278px\u00a0\u00bb custom_margin=\u00a0\u00bb||42px|||\u00a0\u00bb custom_padding=\u00a0\u00bb60px|40px|0px|40px||\u00a0\u00bb animation_style=\u00a0\u00bbzoom\u00a0\u00bb animation_intensity_zoom=\u00a0\u00bb10%\u00a0\u00bb animation=\u00a0\u00bboff\u00a0\u00bb link_option_url_new_window=\u00a0\u00bbon\u00a0\u00bb custom_css_free_form=\u00a0\u00bb\/* Base style *\/||.learn-more {||  display: inline-block;||  font-weight: bold;||  cursor: pointer;||  transition: transform 0.3s ease;||}||||\/* Hover animation *\/||.learn-more:hover {||  transform: scale(1.1); \/* Smooth expansion *\/||}||\u00a0\u00bb border_radii=\u00a0\u00bbon|16px|16px|16px|16px\u00a0\u00bb border_width_all=\u00a0\u00bb2px\u00a0\u00bb border_color_all=\u00a0\u00bb#55876a\u00a0\u00bb border_color_all_image=\u00a0\u00bb#55876a\u00a0\u00bb border_style_all_image=\u00a0\u00bbdouble\u00a0\u00bb image_max_width=\u00a0\u00bb20%\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\">Profitez de rabais sur des produits haut de gamme \u00e9labor\u00e9s \u00e0 partir d\u2019ingr\u00e9dients naturels riches en nutriments!<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb link_option_url=\u00a0\u00bb\/frca\/affiliate\/\u00a0\u00bb link_option_url_new_window=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_blurb title=\u00a0\u00bbAVANTAGES\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb image_icon_background_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb image=\u00a0\u00bbhttps:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2026\/03\/website-icons.png\u00a0\u00bb image_icon_width=\u00a0\u00bb200%\u00a0\u00bb admin_label=\u00a0\u00bbJuice Type\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; header_font=\u00a0\u00bbMontserrat|700||on|||||\u00a0\u00bb header_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_text_color=\u00a0\u00bb#55876a\u00a0\u00bb header_font_size=\u00a0\u00bb25px\u00a0\u00bb header_line_height=\u00a0\u00bb1.5em\u00a0\u00bb body_font=\u00a0\u00bb||||||||\u00a0\u00bb body_text_align=\u00a0\u00bbcenter\u00a0\u00bb body_text_color=\u00a0\u00bb#0a0000&Prime; body_font_size=\u00a0\u00bb16px\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb background_layout=\u00a0\u00bbdark\u00a0\u00bb min_height=\u00a0\u00bb214px\u00a0\u00bb custom_margin=\u00a0\u00bb||42px|||\u00a0\u00bb custom_padding=\u00a0\u00bb60px|40px|0px|40px||\u00a0\u00bb animation_style=\u00a0\u00bbzoom\u00a0\u00bb animation_intensity_zoom=\u00a0\u00bb10%\u00a0\u00bb animation=\u00a0\u00bboff\u00a0\u00bb link_option_url_new_window=\u00a0\u00bbon\u00a0\u00bb custom_css_free_form=\u00a0\u00bb\/* Base style *\/||.learn-more {||  display: inline-block;||  font-weight: bold;||  cursor: pointer;||  transition: transform 0.3s ease;||}||||\/* Hover animation *\/||.learn-more:hover {||  transform: scale(1.1); \/* Smooth expansion *\/||}||\u00a0\u00bb border_radii=\u00a0\u00bbon|16px|16px|16px|16px\u00a0\u00bb border_width_all=\u00a0\u00bb2px\u00a0\u00bb border_color_all=\u00a0\u00bb#55876a\u00a0\u00bb border_color_all_image=\u00a0\u00bb#55876a\u00a0\u00bb border_style_all_image=\u00a0\u00bbdouble\u00a0\u00bb image_max_width=\u00a0\u00bb20%\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\">Profitez des avantages offerts par le programme VIP de Bravenly lorsque vous utilisez et partagez nos produits!<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_blurb title=\u00a0\u00bbCOMMUNAUT\u00c9\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb image_icon_background_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb image=\u00a0\u00bbhttps:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2026\/03\/1-3.png\u00a0\u00bb image_icon_width=\u00a0\u00bb200%\u00a0\u00bb admin_label=\u00a0\u00bbJuice Type\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; header_font=\u00a0\u00bbMontserrat|700||on|||||\u00a0\u00bb header_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_text_color=\u00a0\u00bb#55876a\u00a0\u00bb header_font_size=\u00a0\u00bb25px\u00a0\u00bb header_line_height=\u00a0\u00bb1.5em\u00a0\u00bb body_font=\u00a0\u00bb||||||||\u00a0\u00bb body_text_align=\u00a0\u00bbcenter\u00a0\u00bb body_text_color=\u00a0\u00bb#0a0000&Prime; body_font_size=\u00a0\u00bb16px\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb background_layout=\u00a0\u00bbdark\u00a0\u00bb min_height=\u00a0\u00bb278px\u00a0\u00bb custom_margin=\u00a0\u00bb||42px|||\u00a0\u00bb custom_padding=\u00a0\u00bb60px|40px|0px|40px||\u00a0\u00bb animation_style=\u00a0\u00bbzoom\u00a0\u00bb animation_intensity_zoom=\u00a0\u00bb10%\u00a0\u00bb animation=\u00a0\u00bboff\u00a0\u00bb link_option_url_new_window=\u00a0\u00bbon\u00a0\u00bb custom_css_free_form=\u00a0\u00bb\/* Base style *\/||.learn-more {||  display: inline-block;||  font-weight: bold;||  cursor: pointer;||  transition: transform 0.3s ease;||}||||\/* Hover animation *\/||.learn-more:hover {||  transform: scale(1.1); \/* Smooth expansion *\/||}||\u00a0\u00bb border_radii=\u00a0\u00bbon|16px|16px|16px|16px\u00a0\u00bb border_width_all=\u00a0\u00bb2px\u00a0\u00bb border_color_all=\u00a0\u00bb#55876a\u00a0\u00bb border_color_all_image=\u00a0\u00bb#55876a\u00a0\u00bb border_style_all_image=\u00a0\u00bbdouble\u00a0\u00bb image_max_width=\u00a0\u00bb20%\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\">Venez faire partie d\u2019une communaut\u00e9 qui se soucie de vous, de votre histoire et de votre passion pour nos produits!<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb min_height=\u00a0\u00bb456.2px\u00a0\u00bb custom_margin=\u00a0\u00bb||1px|||\u00a0\u00bb hover_transition_duration=\u00a0\u00bb0ms\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_3,1_3,1_3&Prime; use_custom_gutter=\u00a0\u00bbon\u00a0\u00bb make_equal=\u00a0\u00bbon\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; min_height=\u00a0\u00bb432.2px\u00a0\u00bb custom_margin=\u00a0\u00bb|auto|119px|auto|false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||3px||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb||80px||false|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb||50px||false|false\u00a0\u00bb custom_css_free_form=\u00a0\u00bb\/* === Make ALL carousel cards the SAME HEIGHT &#038; MATCHING SHADOW === *\/||||\/* Make the slide track stretch all slides equally *\/||selector .slick-track,||selector .swiper-wrapper {||  display: flex !important;||  align-items: stretch !important;||}||||\/* Let each slide fill height *\/||selector .slick-slide,||selector .swiper-slide {||  height: auto !important;||}||||\/* Force card containers to stretch equally *\/||selector .et_pb_blurb,||selector .et_pb_text,||selector .dcb-item,||selector .dcb-slide,||selector .dcb-slide-inner {||  flex: 1 1 auto;||  display: flex;||  flex-direction: column;||  justify-content: space-between;||  height: 100%;||  background: #fff; \/* ensure white cards *\/||  box-shadow: 0 4px 20px rgba(0, 0, 0, 0.1); \/* nice even shadow *\/||  border-radius: 8px; \/* optional rounded corners *\/||  padding: 20px; \/* consistent spacing *\/||}||||\/* Keep buttons at bottom if present *\/||selector .et_pb_button_wrapper,||selector .et_pb_button {||  margin-top: auto;||}||||\/* Justify all text *\/||selector p,||selector .et_pb_text,||selector .et_pb_blurb_description {||  text-align: justify;||  text-justify: inter-word;||}\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb link_option_url=\u00a0\u00bb\/vip-customer\/\u00a0\u00bb link_option_url_new_window=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_blurb title=\u00a0\u00bb10% DE R\u00c9DUCTION SUR LES PRODUITS\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb image_icon_background_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb image=\u00a0\u00bbhttps:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2026\/03\/3-2.png\u00a0\u00bb image_icon_width=\u00a0\u00bb200%\u00a0\u00bb admin_label=\u00a0\u00bbJuice Type\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; header_font=\u00a0\u00bbMontserrat|700||on|||||\u00a0\u00bb header_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_text_color=\u00a0\u00bb#55876a\u00a0\u00bb header_font_size=\u00a0\u00bb25px\u00a0\u00bb header_line_height=\u00a0\u00bb1.5em\u00a0\u00bb body_font=\u00a0\u00bb||||||||\u00a0\u00bb body_text_align=\u00a0\u00bbcenter\u00a0\u00bb body_text_color=\u00a0\u00bb#0a0000&Prime; body_font_size=\u00a0\u00bb16px\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb background_layout=\u00a0\u00bbdark\u00a0\u00bb min_height=\u00a0\u00bb278px\u00a0\u00bb custom_margin=\u00a0\u00bb||42px|||\u00a0\u00bb custom_padding=\u00a0\u00bb60px|40px|0px|40px||\u00a0\u00bb animation_style=\u00a0\u00bbzoom\u00a0\u00bb animation_intensity_zoom=\u00a0\u00bb10%\u00a0\u00bb animation=\u00a0\u00bboff\u00a0\u00bb link_option_url_new_window=\u00a0\u00bbon\u00a0\u00bb custom_css_free_form=\u00a0\u00bb\/* Base style *\/||.learn-more {||  display: inline-block;||  font-weight: bold;||  cursor: pointer;||  transition: transform 0.3s ease;||}||||\/* Hover animation *\/||.learn-more:hover {||  transform: scale(1.1); \/* Smooth expansion *\/||}||\u00a0\u00bb border_radii=\u00a0\u00bbon|16px|16px|16px|16px\u00a0\u00bb border_width_all=\u00a0\u00bb2px\u00a0\u00bb border_color_all=\u00a0\u00bb#55876a\u00a0\u00bb border_color_all_image=\u00a0\u00bb#55876a\u00a0\u00bb border_style_all_image=\u00a0\u00bbdouble\u00a0\u00bb image_max_width=\u00a0\u00bb20%\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\">Profitez de cette r\u00e9duction exclusive \u00e0 vie lorsque vous achetez des produits Bravenly.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb link_option_url=\u00a0\u00bb\/frca\/affiliate\/\u00a0\u00bb link_option_url_new_window=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_blurb title=\u00a0\u00bbABONNEMENT \u00c0 VIE:\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb image_icon_background_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb image=\u00a0\u00bbhttps:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2026\/03\/6-2.png\u00a0\u00bb image_icon_width=\u00a0\u00bb200%\u00a0\u00bb admin_label=\u00a0\u00bbJuice Type\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; header_font=\u00a0\u00bbMontserrat|700||on|||||\u00a0\u00bb header_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_text_color=\u00a0\u00bb#55876a\u00a0\u00bb header_font_size=\u00a0\u00bb25px\u00a0\u00bb header_line_height=\u00a0\u00bb1.5em\u00a0\u00bb body_font=\u00a0\u00bb||||||||\u00a0\u00bb body_text_align=\u00a0\u00bbcenter\u00a0\u00bb body_text_color=\u00a0\u00bb#0a0000&Prime; body_font_size=\u00a0\u00bb16px\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb background_layout=\u00a0\u00bbdark\u00a0\u00bb min_height=\u00a0\u00bb214px\u00a0\u00bb custom_margin=\u00a0\u00bb||42px|||\u00a0\u00bb custom_padding=\u00a0\u00bb60px|40px|0px|40px||\u00a0\u00bb animation_style=\u00a0\u00bbzoom\u00a0\u00bb animation_intensity_zoom=\u00a0\u00bb10%\u00a0\u00bb animation=\u00a0\u00bboff\u00a0\u00bb link_option_url_new_window=\u00a0\u00bbon\u00a0\u00bb custom_css_free_form=\u00a0\u00bb\/* Base style *\/||.learn-more {||  display: inline-block;||  font-weight: bold;||  cursor: pointer;||  transition: transform 0.3s ease;||}||||\/* Hover animation *\/||.learn-more:hover {||  transform: scale(1.1); \/* Smooth expansion *\/||}||\u00a0\u00bb border_radii=\u00a0\u00bbon|16px|16px|16px|16px\u00a0\u00bb border_width_all=\u00a0\u00bb2px\u00a0\u00bb border_color_all=\u00a0\u00bb#55876a\u00a0\u00bb border_color_all_image=\u00a0\u00bb#55876a\u00a0\u00bb border_style_all_image=\u00a0\u00bbdouble\u00a0\u00bb image_max_width=\u00a0\u00bb20%\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\">Payez un montant unique de 14,99$CAD et b\u00e9n\u00e9ficiez d\u2019un abonnement \u00e0 vie \u00e0 notre programme de fid\u00e9lit\u00e9 VIP.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_blurb title=\u00a0\u00bbBRAVENLY CASH\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb image_icon_background_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb image=\u00a0\u00bbhttps:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2026\/03\/5-2.png\u00a0\u00bb image_icon_width=\u00a0\u00bb200%\u00a0\u00bb admin_label=\u00a0\u00bbJuice Type\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; header_font=\u00a0\u00bbMontserrat|700||on|||||\u00a0\u00bb header_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_text_color=\u00a0\u00bb#55876a\u00a0\u00bb header_font_size=\u00a0\u00bb25px\u00a0\u00bb header_line_height=\u00a0\u00bb1.5em\u00a0\u00bb body_font=\u00a0\u00bb||||||||\u00a0\u00bb body_text_align=\u00a0\u00bbcenter\u00a0\u00bb body_text_color=\u00a0\u00bb#0a0000&Prime; body_font_size=\u00a0\u00bb16px\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb background_layout=\u00a0\u00bbdark\u00a0\u00bb min_height=\u00a0\u00bb278px\u00a0\u00bb custom_margin=\u00a0\u00bb||42px|||\u00a0\u00bb custom_padding=\u00a0\u00bb60px|40px|0px|40px||\u00a0\u00bb animation_style=\u00a0\u00bbzoom\u00a0\u00bb animation_intensity_zoom=\u00a0\u00bb10%\u00a0\u00bb animation=\u00a0\u00bboff\u00a0\u00bb link_option_url_new_window=\u00a0\u00bbon\u00a0\u00bb custom_css_free_form=\u00a0\u00bb\/* Base style *\/||.learn-more {||  display: inline-block;||  font-weight: bold;||  cursor: pointer;||  transition: transform 0.3s ease;||}||||\/* Hover animation *\/||.learn-more:hover {||  transform: scale(1.1); \/* Smooth expansion *\/||}||\u00a0\u00bb border_radii=\u00a0\u00bbon|16px|16px|16px|16px\u00a0\u00bb border_width_all=\u00a0\u00bb2px\u00a0\u00bb border_color_all=\u00a0\u00bb#55876a\u00a0\u00bb border_color_all_image=\u00a0\u00bb#55876a\u00a0\u00bb border_style_all_image=\u00a0\u00bbdouble\u00a0\u00bb image_max_width=\u00a0\u00bb20%\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\">Lorsqu\u2019un client ach\u00e8te des produits Bravenly en utilisant votre lien, vous recevez 10% de remise en argent magasinage Bravenly (Bravenly Cash).<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb|1px||||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_button button_url=\u00a0\u00bb\/frca\/\u00a0\u00bb button_text=\u00a0\u00bbACCUEIL\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb button_text_tablet=\u00a0\u00bbACHETER LES PRODUITS\u00a0\u00bb button_text_phone=\u00a0\u00bbACHETER LES PRODUITS\u00a0\u00bb button_text_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb22px\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_color=\u00a0\u00bbgcid-primary-color\u00a0\u00bb button_border_width=\u00a0\u00bb2px\u00a0\u00bb button_border_color=\u00a0\u00bbgcid-body-color\u00a0\u00bb button_font=\u00a0\u00bbLato||||||||\u00a0\u00bb custom_margin=\u00a0\u00bb10px|10px|10px|10px|false|false\u00a0\u00bb custom_padding=\u00a0\u00bb10px||10px||false|false\u00a0\u00bb button_text_size_tablet=\u00a0\u00bb22px\u00a0\u00bb button_text_size_phone=\u00a0\u00bb16px\u00a0\u00bb button_text_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb hover_transition_duration_tablet=\u00a0\u00bb\u00a0\u00bb hover_transition_duration_phone=\u00a0\u00bb0ms\u00a0\u00bb hover_transition_duration_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-body-color%22:%91%22button_border_color%22%93,%22gcid-primary-color%22:%91%22button_bg_color%22%93}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbSplit Section\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb0px||0px|\u00a0\u00bb animation_style=\u00a0\u00bbfold\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_fold=\u00a0\u00bb4%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbSplit Section\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb0px||0px|\u00a0\u00bb animation_style=\u00a0\u00bbfold\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_fold=\u00a0\u00bb4%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CLIENTS VIP BRAVENLYPR\u00c9PAREZ-VOUS \u00c0 UN TRAITEMENT VIP Si vous appr\u00e9ciez les produits haut de gamme qui donnent de vrais r\u00e9sultats, devenez client VIP et profitez de rabais, de cadeaux et d\u2019autres avantages incroyables \u00e0 chaque achat. Chez Bravenly, nous traitons nos clients VIP comme des membres de notre famille. Pour vous inscrire, veuillez ajouter les [&hellip;]<\/p>\n","protected":false},"author":191432657,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"class_list":["post-53277","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/jadenmartin.bravenlyglobal.com\/frca\/wp-json\/wp\/v2\/pages\/53277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jadenmartin.bravenlyglobal.com\/frca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/jadenmartin.bravenlyglobal.com\/frca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/jadenmartin.bravenlyglobal.com\/frca\/wp-json\/wp\/v2\/users\/191432657"}],"replies":[{"embeddable":true,"href":"https:\/\/jadenmartin.bravenlyglobal.com\/frca\/wp-json\/wp\/v2\/comments?post=53277"}],"version-history":[{"count":4,"href":"https:\/\/jadenmartin.bravenlyglobal.com\/frca\/wp-json\/wp\/v2\/pages\/53277\/revisions"}],"predecessor-version":[{"id":54468,"href":"https:\/\/jadenmartin.bravenlyglobal.com\/frca\/wp-json\/wp\/v2\/pages\/53277\/revisions\/54468"}],"wp:attachment":[{"href":"https:\/\/jadenmartin.bravenlyglobal.com\/frca\/wp-json\/wp\/v2\/media?parent=53277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}